<br />
<b>Warning</b>:  Undefined array key "REQUEST_SCHEME" in <b>/home/vunderatdm/wordpress/wp-content/advanced-cache.php</b> on line <b>27</b><br />
{"id":1127,"date":"2021-05-24T13:49:02","date_gmt":"2021-05-24T11:49:02","guid":{"rendered":"https:\/\/vunderatert.lu\/?p=1127"},"modified":"2023-02-02T16:18:15","modified_gmt":"2023-02-02T15:18:15","slug":"conge-au-jardin-on-plante","status":"publish","type":"post","link":"https:\/\/vunderatert.lu\/2021\/05\/conge-au-jardin-on-plante\/","title":{"rendered":"cong\u00e9 au jardin: on plante !"},"content":{"rendered":"\n<p>Nous avons retard\u00e9 au maximum l&#8217;installation des cultures d&#8217;\u00e9t\u00e9 en plein air, ces aubergines, tomates et concombres n&#8217;appr\u00e9ciant pas le froid ambiant. Mais on ne peut plus attendre\u00a0: elles souffrent de manque de place et de nutriments dans notre p\u00e9pini\u00e8re.<\/p>\n\n\n\n<p>Cette semaine de Pentec\u00f4te sera donc consacr\u00e9e \u00e0 de nombreuses plantations et toutes les personnes int\u00e9ress\u00e9es sont bienvenues pour nous aider, quelques heures, seules ou en famille. Le programme ci-dessous pourrait changer, mais donne une id\u00e9e des activit\u00e9s possibles\u00a0:<\/p>\n\n\n\n<ul><li>Lundi 24 soir (16 \u00e0 20h): tomates, avec Bertrand<\/li><li>Mardi 25 matin (9 \u00e0 12h) : poireaux, avec Braam<\/li><li>Mardi 25 apr\u00e8s-midi (13 \u00e0 17h) : tomates, avec Sam<\/li><li>Mercredi 26 matin (9 \u00e0 12h): fraises et pr\u00e9parations courges et concombres, avec Braam<\/li><li>Mercredi 26 soir (17 \u00e0 20h): b\u00e2chage de 2 tunnels sur <a rel=\"noreferrer noopener\" href=\"https:\/\/tiny.cc\/nagem-acces\" target=\"_blank\">notre terrain \u00e0 Nagem<\/a>, avec Bertrand<\/li><li>Jeudi 27 matin (9 \u00e0 13h): verdures, avec Braam<\/li><li>jeudi 27 soir (16 \u00e0 20h): encore \u00e0 d\u00e9finir, avec Bertrand<\/li><li>Vendredi 28 matin (8 \u00e0 13h): r\u00e9coltes pour la distribution du jour, puis courges<\/li><li>Vendredi 28 apr\u00e8s-midi (14 \u00e0 19h): courges et concombres avec Sam et Bertrand<\/li><\/ul>\n\n\n\n<div class=\"is-layout-flex wp-container-3 wp-block-columns\">\n<div class=\"is-layout-flow wp-block-column\" style=\"flex-basis:50%\">\n<p>Pour am\u00e9liorer la vie du sol (biodiversit\u00e9 et fertilit\u00e9), nous planterons une partie de ces cultures sous un \u00e9pais mulch de foin dont la d\u00e9composition nourrira les invert\u00e9br\u00e9s et prot\u00e8gera le sol des s\u00e9cheresses de l&#8217;\u00e9t\u00e9. Il sera peut-\u00eatre aussi un refuge privil\u00e9gi\u00e9 des mulots et campagnols&#8230; affaire \u00e0 suivre.<\/p>\n<\/div>\n\n\n\n<div class=\"is-layout-flow wp-block-column\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" src=\"https:\/\/vunderatert.lu\/wp-content\/uploads\/2021\/05\/mai2021-cultures-sur-foin-1024x576.jpeg\" alt=\"\" class=\"wp-image-1128\" srcset=\"https:\/\/vunderatert.lu\/wp-content\/uploads\/2021\/05\/mai2021-cultures-sur-foin-1024x576.jpeg 1024w, https:\/\/vunderatert.lu\/wp-content\/uploads\/2021\/05\/mai2021-cultures-sur-foin-300x169.jpeg 300w, https:\/\/vunderatert.lu\/wp-content\/uploads\/2021\/05\/mai2021-cultures-sur-foin-768x432.jpeg 768w, https:\/\/vunderatert.lu\/wp-content\/uploads\/2021\/05\/mai2021-cultures-sur-foin-1536x864.jpeg 1536w, https:\/\/vunderatert.lu\/wp-content\/uploads\/2021\/05\/mai2021-cultures-sur-foin-1320x743.jpeg 1320w, https:\/\/vunderatert.lu\/wp-content\/uploads\/2021\/05\/mai2021-cultures-sur-foin.jpeg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>Les enfants sont bienvenus lors de ces activit\u00e9s au jardin, sous la responsabilit\u00e9 de leurs parents.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous avons retard\u00e9 au maximum l&#8217;installation des cultures d&#8217;\u00e9t\u00e9 en plein air, ces aubergines, tomates et concombres n&#8217;appr\u00e9ciant pas le froid ambiant. Mais on ne peut plus attendre\u00a0: elles souffrent de manque de place et de nutriments dans notre p\u00e9pini\u00e8re. Cette semaine de Pentec\u00f4te sera donc consacr\u00e9e \u00e0 de nombreuses plantations et toutes les personnes&hellip;&nbsp;<a href=\"https:\/\/vunderatert.lu\/2021\/05\/conge-au-jardin-on-plante\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">cong\u00e9 au jardin: on plante !<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1129,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false},"categories":[12],"tags":[45,46],"_links":{"self":[{"href":"https:\/\/vunderatert.lu\/wp-json\/wp\/v2\/posts\/1127"}],"collection":[{"href":"https:\/\/vunderatert.lu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vunderatert.lu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vunderatert.lu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vunderatert.lu\/wp-json\/wp\/v2\/comments?post=1127"}],"version-history":[{"count":1,"href":"https:\/\/vunderatert.lu\/wp-json\/wp\/v2\/posts\/1127\/revisions"}],"predecessor-version":[{"id":1220,"href":"https:\/\/vunderatert.lu\/wp-json\/wp\/v2\/posts\/1127\/revisions\/1220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vunderatert.lu\/wp-json\/wp\/v2\/media\/1129"}],"wp:attachment":[{"href":"https:\/\/vunderatert.lu\/wp-json\/wp\/v2\/media?parent=1127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vunderatert.lu\/wp-json\/wp\/v2\/categories?post=1127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vunderatert.lu\/wp-json\/wp\/v2\/tags?post=1127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}